{"id":3169,"date":"2022-02-08T10:02:08","date_gmt":"2022-02-08T01:02:08","guid":{"rendered":"https:\/\/www.iee.jp\/pes\/?p=3169"},"modified":"2022-02-08T10:02:08","modified_gmt":"2022-02-08T01:02:08","slug":"nl_202202","status":"publish","type":"post","link":"https:\/\/www.iee.jp\/pes\/nl_202202\/","title":{"rendered":"\u96fb\u529b\u30fb\u30a8\u30cd\u30eb\u30ae\u30fc\u90e8\u9580\u3000\u30cb\u30e5\u30fc\u30b9\u30ec\u30bf\u30fc\u30002\u6708\u53f7"},"content":{"rendered":"<p>2\u6708\u53f7\u304c\u516c\u958b\u3055\u308c\u307e\u3057\u305f\u3002\u305c\u3072\u3054\u89a7\u304f\u3060\u3055\u3044\uff01<\/p>\n<p>\u4eca\u6708\u306e\u5185\u5bb9\u306f\uff0c<\/p>\n<ul>\n<li><a href=\"https:\/\/www.iee.jp\/pes\/wp-content\/uploads\/sites\/3\/2022\/02\/202202-B-NL.pdf\">\u30cb\u30e5\u30fc\u30b9\u30ec\u30bf\u30fc2\u6708\u53f7<\/a>\n<ul>\n<li>\u4ee4\u548c4\u5e74\u96fb\u6c17\u5b66\u4f1a \u96fb\u529b\u30fb\u30a8\u30cd\u30eb\u30ae\u30fc\u90e8\u9580\u5927\u4f1a\u306e\u958b\u50ac\u6848\u5185\u3068\u8ad6\u6587\u52df\u96c6\uff08\u7b2c1\u5831\uff09<\/li>\n<li>\u4ee4\u548c3\u5e74\u96fb\u529b\u30fb\u30a8\u30cd\u30eb\u30ae\u30fc\u90e8\u9580\u5927\u4f1a\u5831\u544a<\/li>\n<li>\u7528\u8a9e\u89e3\u8aac\uff08\u7b2c131\u56de\u30c6\u30fc\u30de\uff1a\u30b3\u30f3\u30bb\u30f3\u30b5\u30b9\u4e88\u5831\uff09<\/li>\n<li>\u7814\u7a76\u30b0\u30eb\u30fc\u30d7\u7d39\u4ecb\uff1a\u65e5\u672c\u5927\u5b66 \u5de5\u5b66\u90e8 \u5236\u5fa1\u5de5\u5b66\u7814\u7a76\u5ba4<\/li>\n<li>\u5b66\u754c\u60c5\u5831\uff1aInternational Conference on Grounding &amp; Lightning Physics and Effects\u5831\u544a<\/li>\n<li>\u6d77\u5916\u99d0\u5728\u8a18\u4e8b\uff1a\uff08\u72ec\uff09\u30e6\u30fc\u30ea\u30c3\u30d2\u7814\u7a76\u6240\u6ede\u5728\u8a18<\/li>\n<li>\u8abf\u67fb\u7814\u7a76\u59d4\u54e1\u4f1a\u30ec\u30dd\u30fc\u30c8\uff1a\u592a\u967d\u5149\u767a\u96fb\u30b7\u30b9\u30c6\u30e0\u306e\u6301\u7d9a\u7684\u5229\u7528\u6280\u8853\u8abf\u67fb\u5c02\u9580\u59d4\u54e1\u4f1a\u8a2d\u7f6e\u306b\u3064\u3044\u3066<\/li>\n<li>\u96fb\u529b\u30fb\u30a8\u30cd\u30eb\u30ae\u30fc\u90e8\u9580\u8a8c\u30002022\u5e742\u6708\u53f7\u76ee\u6b21<\/li>\n<li>\u5b66\u4f1a\u30ab\u30ec\u30f3\u30c0\u30fc<\/li>\n<\/ul>\n<\/li>\n<\/ul>\n<p>\u3067\u3059\uff01<\/p>\n","protected":false},"excerpt":{"rendered":"<p>2\u6708\u53f7\u304c\u516c\u958b\u3055\u308c\u307e\u3057\u305f\u3002\u305c\u3072\u3054\u89a7\u304f\u3060\u3055\u3044\uff01 \u4eca\u6708\u306e\u5185\u5bb9\u306f\uff0c \u30cb\u30e5\u30fc\u30b9\u30ec\u30bf\u30fc2\u6708\u53f7 \u4ee4\u548c4\u5e74\u96fb\u6c17\u5b66\u4f1a \u96fb\u529b\u30fb\u30a8\u30cd\u30eb\u30ae\u30fc\u90e8\u9580\u5927\u4f1a\u306e\u958b\u50ac\u6848\u5185\u3068\u8ad6\u6587\u52df\u96c6\uff08\u7b2c1\u5831\uff09 \u4ee4\u548c3\u5e74\u96fb\u529b\u30fb\u30a8\u30cd\u30eb\u30ae\u30fc\u90e8\u9580\u5927\u4f1a\u5831\u544a \u7528\u8a9e\u89e3\u8aac\uff08\u7b2c131\u56de\u30c6\u30fc\u30de [&hellip;]<\/p>\n","protected":false},"author":9,"featured_media":957,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"advanced_seo_description":"","jetpack_seo_html_title":"","jetpack_seo_noindex":false,"jetpack_seo_schema_type":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"jetpack_publicize_message":"\u96fb\u529b\u30fb\u30a8\u30cd\u30eb\u30ae\u30fc\u90e8\u9580\u3000\u30cb\u30e5\u30fc\u30b9\u30ec\u30bf\u30fc\u30002\u6708\u53f7\u304c\u516c\u958b\u3055\u308c\u307e\u3057\u305f\uff01\r\n#\u96fb\u6c17\u5b66\u4f1a #\u96fb\u529b #\u30a8\u30cd\u30eb\u30ae\u30fc #\u96fb\u6c17","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false,"vk-ltc-link":"","vk-ltc-target":"0"},"categories":[1,2],"tags":[],"class_list":["post-3169","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-event","category-news"],"acf":[],"jetpack_publicize_connections":[],"jetpack-related-posts":[],"jetpack_shortlink":"https:\/\/wp.me\/pbuf8C-P7","jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/www.iee.jp\/pes\/wp-content\/uploads\/sites\/3\/2020\/02\/NL-ec-e1581068188901.jpg","_links":{"self":[{"href":"https:\/\/www.iee.jp\/pes\/wp-json\/wp\/v2\/posts\/3169","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.iee.jp\/pes\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.iee.jp\/pes\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.iee.jp\/pes\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/www.iee.jp\/pes\/wp-json\/wp\/v2\/comments?post=3169"}],"version-history":[{"count":1,"href":"https:\/\/www.iee.jp\/pes\/wp-json\/wp\/v2\/posts\/3169\/revisions"}],"predecessor-version":[{"id":3171,"href":"https:\/\/www.iee.jp\/pes\/wp-json\/wp\/v2\/posts\/3169\/revisions\/3171"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.iee.jp\/pes\/wp-json\/wp\/v2\/media\/957"}],"wp:attachment":[{"href":"https:\/\/www.iee.jp\/pes\/wp-json\/wp\/v2\/media?parent=3169"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.iee.jp\/pes\/wp-json\/wp\/v2\/categories?post=3169"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.iee.jp\/pes\/wp-json\/wp\/v2\/tags?post=3169"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}